{"id":148455,"date":"2026-09-02T13:31:23","date_gmt":"2026-09-02T11:31:23","guid":{"rendered":"https:\/\/www.shalom.it\/?p=148455"},"modified":"2026-09-02T13:43:24","modified_gmt":"2026-09-02T11:43:24","slug":"israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d","status":"publish","type":"post","link":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/","title":{"rendered":"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D"},"content":{"rendered":"<p style=\"text-align: justify;\">Era stato considerato \u201cinoperabile\u201d. Tuttavia, un\u2019\u00e9quipe di chirurghi israeliani \u00e8 riuscita a sottoporlo all\u2019intervento. A 14 anni, Mark aveva ricevuto una nuova diagnosi di tumore, dopo aver sconfitto, a soli due anni, un primo cancro. Questa volta si trattava di un osteosarcoma, una forma rara e aggressiva di tumore osseo, localizzato nella zona pelvica e accompagnato da metastasi ai polmoni. A riportarlo \u00e8 il Jerusalem Post.<br \/>\nIn Russia, dove viveva, il caso era stato considerato inoperabile a causa della localizzazione e dell\u2019estensione della malattia. La madre di Mark, per\u00f2, non si \u00e8 arresa e ha portato il figlio in Israele, al Clalit Schneider Children\u2019s Medical Center. Qui il ragazzo \u00e8 stato sottoposto a una chemioterapia mirata, coordinata dalla dottoressa Orli Michaeli. Il trattamento ha dato una risposta importante: le metastasi polmonari sono scomparse e il tumore primario si \u00e8 ridotto.<br \/>\nA quel punto, un\u2019\u00e9quipe congiunta di specialisti del Clalit-Schneider e del Clalit-Beilinson Hospital ha deciso di affrontare una sfida considerata fino a quel momento impossibile. Per preparare l\u2019intervento sono state necessarie numerose ore di pianificazione digitale. L\u2019obiettivo non era soltanto rimuovere completamente il tumore, ma anche ripristinare la mobilit\u00e0 del ragazzo.<br \/>\nL\u2019intervento, eseguito quando Mark aveva 15 anni, \u00e8 durato 19 ore. I chirurghi hanno rimosso circa met\u00e0 del suo bacino, sostituendola con un impianto in titanio e polimero avanzato, progettato su misura e stampato in 3D. \u201cQuesto \u00e8 stato uno dei casi pi\u00f9 complessi e impegnativi che abbiamo mai affrontato\u201d, ha spiegato il dottor Israel Weiss, responsabile dell\u2019Unit\u00e0 di Oncologia Ortopedica di entrambi gli ospedali.<br \/>\nIl dottor Arie Greenberg, specialista in Chirurgia protesica e Oncologia ortopedica al Clalit-Beilinson, ha definito l\u2019utilizzo combinato della Chirurgia oncologica avanzata e della Progettazione tridimensionale personalizzata un vero e proprio \u201csalto quantico\u201d nel campo dell\u2019oncologia chirurgica.<br \/>\nL\u2019intervento \u00e8 stato possibile grazie alla collaborazione tra diverse \u00e9quipe specialistiche. \u201cInvece di accettare che il tumore fosse inoperabile, le nostre \u00e9quipe hanno unito competenze diverse, progettazione tridimensionale personalizzata e tecnologie avanzate di stampa. Questa collaborazione apre un nuovo orizzonte di possibilit\u00e0\u201d, ha spiegato Weiss.<br \/>\nMark \u00e8 ora in fase di recupero e sta affrontando la riabilitazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Era stato considerato \u201cinoperabile\u201d. Tuttavia, un\u2019\u00e9quipe di chirurghi israeliani \u00e8 riuscita a sottoporlo all\u2019intervento. A 14 anni, Mark aveva ricevuto una nuova diagnosi di tumore, dopo aver sconfitto, a soli due anni, un primo cancro. Questa volta si trattava di un osteosarcoma, una forma rara e aggressiva di tumore osseo, localizzato nella zona pelvica e [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":148456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-148455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-israele"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D - Shalom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D - Shalom\" \/>\n<meta property=\"og:description\" content=\"Era stato considerato \u201cinoperabile\u201d. Tuttavia, un\u2019\u00e9quipe di chirurghi israeliani \u00e8 riuscita a sottoporlo all\u2019intervento. A 14 anni, Mark aveva ricevuto una nuova diagnosi di tumore, dopo aver sconfitto, a soli due anni, un primo cancro. Questa volta si trattava di un osteosarcoma, una forma rara e aggressiva di tumore osseo, localizzato nella zona pelvica e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"Shalom\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T11:31:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T11:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/www.shalom.it\/#\/schema\/person\/d6d60e821a49d2a420ffe01f7af79dd8\"},\"headline\":\"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D\",\"datePublished\":\"2026-09-02T11:31:23+00:00\",\"dateModified\":\"2026-09-02T11:43:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/\"},\"wordCount\":364,\"image\":{\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp\",\"articleSection\":[\"ISRAELE\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/\",\"url\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/\",\"name\":\"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D - Shalom\",\"isPartOf\":{\"@id\":\"https:\/\/www.shalom.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp\",\"datePublished\":\"2026-09-02T11:31:23+00:00\",\"dateModified\":\"2026-09-02T11:43:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.shalom.it\/#\/schema\/person\/d6d60e821a49d2a420ffe01f7af79dd8\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage\",\"url\":\"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp\",\"contentUrl\":\"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp\",\"width\":1400,\"height\":711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.shalom.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.shalom.it\/#website\",\"url\":\"https:\/\/www.shalom.it\/\",\"name\":\"Shalom\",\"description\":\"Il Magazine della comunit\u00e0 ebraica di Roma\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.shalom.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.shalom.it\/#\/schema\/person\/d6d60e821a49d2a420ffe01f7af79dd8\",\"name\":\"Redazione\",\"url\":\"https:\/\/www.shalom.it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D - Shalom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/","og_locale":"it_IT","og_type":"article","og_title":"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D - Shalom","og_description":"Era stato considerato \u201cinoperabile\u201d. Tuttavia, un\u2019\u00e9quipe di chirurghi israeliani \u00e8 riuscita a sottoporlo all\u2019intervento. A 14 anni, Mark aveva ricevuto una nuova diagnosi di tumore, dopo aver sconfitto, a soli due anni, un primo cancro. Questa volta si trattava di un osteosarcoma, una forma rara e aggressiva di tumore osseo, localizzato nella zona pelvica e [&hellip;]","og_url":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/","og_site_name":"Shalom","article_published_time":"2026-09-02T11:31:23+00:00","article_modified_time":"2026-09-02T11:43:24+00:00","og_image":[{"width":1400,"height":711,"url":"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp","type":"image\/webp"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#article","isPartOf":{"@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/"},"author":{"name":"Redazione","@id":"https:\/\/www.shalom.it\/#\/schema\/person\/d6d60e821a49d2a420ffe01f7af79dd8"},"headline":"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D","datePublished":"2026-09-02T11:31:23+00:00","dateModified":"2026-09-02T11:43:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/"},"wordCount":364,"image":{"@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp","articleSection":["ISRAELE"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/","url":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/","name":"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D - Shalom","isPartOf":{"@id":"https:\/\/www.shalom.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage"},"image":{"@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp","datePublished":"2026-09-02T11:31:23+00:00","dateModified":"2026-09-02T11:43:24+00:00","author":{"@id":"https:\/\/www.shalom.it\/#\/schema\/person\/d6d60e821a49d2a420ffe01f7af79dd8"},"breadcrumb":{"@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#primaryimage","url":"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp","contentUrl":"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp","width":1400,"height":711},{"@type":"BreadcrumbList","@id":"https:\/\/www.shalom.it\/israele\/israele-15enne-operato-per-tumore-sostituita-meta-del-bacino-con-una-protesi-stampata-in-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shalom.it\/"},{"@type":"ListItem","position":2,"name":"Israele, 15enne operato per tumore: sostituita met\u00e0 del bacino con una protesi stampata in 3D"}]},{"@type":"WebSite","@id":"https:\/\/www.shalom.it\/#website","url":"https:\/\/www.shalom.it\/","name":"Shalom","description":"Il Magazine della comunit\u00e0 ebraica di Roma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shalom.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.shalom.it\/#\/schema\/person\/d6d60e821a49d2a420ffe01f7af79dd8","name":"Redazione","url":"https:\/\/www.shalom.it\/author\/redazione\/"}]}},"jetpack_featured_media_url":"https:\/\/www.shalom.it\/wp-content\/uploads\/2026\/09\/Sala-operatoria-1.webp","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/posts\/148455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/comments?post=148455"}],"version-history":[{"count":2,"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/posts\/148455\/revisions"}],"predecessor-version":[{"id":148459,"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/posts\/148455\/revisions\/148459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/media\/148456"}],"wp:attachment":[{"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/media?parent=148455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/categories?post=148455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shalom.it\/wp-json\/wp\/v2\/tags?post=148455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}